{"id":4558,"date":"2022-01-12T11:35:21","date_gmt":"2022-01-12T10:35:21","guid":{"rendered":"http:\/\/wp.ebalta.com\/?post_type=dlp_document&#038;p=4558"},"modified":"2026-04-28T12:39:23","modified_gmt":"2026-04-28T10:39:23","slug":"ebablock-k-08","status":"publish","type":"dlp_document","link":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/","title":{"rendered":"ebablock\u00ae K 08"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:40px;--awb-padding-bottom-small:20px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-margin-bottom:0px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:48;line-height:1.5;\">ebablock\u00ae K 08<\/h1><\/div><ul style=\"--awb-line-height:28.9px;--awb-icon-width:28.9px;--awb-icon-height:28.9px;--awb-icon-margin:11.9px;--awb-content-margin:40.8px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default fusion-checklist-divider type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-chevron-right fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><strong>Colour:\u00a0<\/strong>salmon<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-chevron-right fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><strong>Density at 20\u00b0C:<\/strong> 1.35 \u00b1 0.04 g\/cm\u00b3<\/p>\n<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-chevron-right fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p><strong>Coefficient of linear expansion: <\/strong>approx. 150<\/p>\n<\/div><\/li><\/ul><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"429\" alt=\"ebablock\u00ae K 08von der ebalta Kunststoff GmbH\" title=\"ebablock K 08 &#8211; Model made of polyurethane block material\" src=\"https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1.jpg\" class=\"img-responsive wp-image-7043\" srcset=\"https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1-200x143.jpg 200w, https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1-400x286.jpg 400w, https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1.jpg 600w\" sizes=\"(max-width: 860px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:25px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-bottom:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:26;line-height:1.46;\">Downloads<\/h3><\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-1 fusion-button-span-yes fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color6);--button_accent_hover_color:var(--awb-color8);--button_border_hover_color:#ffffff;--button_gradient_top_color:#ffffff;--button_gradient_bottom_color:#ffffff;--button_gradient_top_color_hover:#ffffff;--button_gradient_bottom_color_hover:#ffffff;--button_margin-top:15px;\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Download datasheet\" aria-label=\"Download datasheet\" href=\"https:\/\/ebalta.com\/downloads\/en\/datasheet\/ebablock-k-08.pdf\"><i class=\"fa-file-pdf far awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Datasheet<\/span><\/a><\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-2 fusion-button-span-yes fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color6);--button_accent_hover_color:var(--awb-color8);--button_border_hover_color:#ffffff;--button_gradient_top_color:#ffffff;--button_gradient_bottom_color:#ffffff;--button_gradient_top_color_hover:#ffffff;--button_gradient_bottom_color_hover:#ffffff;--button_margin-top:15px;\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Download Milling Parameters\" aria-label=\"Download Milling Parameters\" href=\"https:\/\/ebalta.com\/downloads\/en\/milling-parameter\/ebablock-k-08.pdf\"><i class=\"fa-file-pdf far awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Milling Parameters<\/span><\/a><\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-3 fusion-button-span-yes fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color6);--button_accent_hover_color:var(--awb-color8);--button_border_hover_color:#ffffff;--button_gradient_top_color:#ffffff;--button_gradient_bottom_color:#ffffff;--button_gradient_top_color_hover:#ffffff;--button_gradient_bottom_color_hover:#ffffff;--button_margin-top:15px;\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"Download adhesive K 08\" aria-label=\"Download adhesive K 08\" href=\"https:\/\/ebalta.com\/downloads\/en\/datasheet\/adhesive-k-08.pdf\"><i class=\"fa-file-pdf far awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Adhesive K 08<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:40px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-margin-top-small:20px;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-bottom:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:26;line-height:1.46;\">Material properties<\/h3><\/div><ul style=\"--awb-line-height:28.9px;--awb-icon-width:28.9px;--awb-icon-height:28.9px;--awb-icon-margin:11.9px;--awb-content-margin:40.8px;\" class=\"fusion-checklist fusion-checklist-2 fusion-checklist-default fusion-checklist-divider type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-chevron-right fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">unprocessed block<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-chevron-right fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">highly abrasion resistant<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-chevron-right fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">impact resistant<\/div><\/li><\/ul><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:40px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-margin-top-small:20px;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-bottom:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:26;line-height:1.46;\">Applications<\/h3><\/div><ul style=\"--awb-line-height:28.9px;--awb-icon-width:28.9px;--awb-icon-height:28.9px;--awb-icon-margin:11.9px;--awb-content-margin:40.8px;\" class=\"fusion-checklist fusion-checklist-3 fusion-checklist-default fusion-checklist-divider type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-chevron-right fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Core boxes<\/div><\/li><\/ul><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:40px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-margin-top-small:20px;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-bottom:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:26;line-height:1.46;\">Delivery options<\/h3><\/div><ul style=\"--awb-line-height:28.9px;--awb-icon-width:28.9px;--awb-icon-height:28.9px;--awb-icon-margin:11.9px;--awb-content-margin:40.8px;\" class=\"fusion-checklist fusion-checklist-4 fusion-checklist-default fusion-checklist-divider type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon fa-chevron-right fas\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<p>Block, custom-cast<\/p>\n<\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\n","protected":false},"author":1,"featured_media":7043,"template":"","doc_categories":[236],"doc_tags":[279],"doc_author":[],"file_type":[40],"class_list":["post-4558","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-polyurethane-blocks-individual-dimensions","doc_tags-kernkaesten-en","file_type-pdf"],"download_url":"https:\/\/ebalta.com\/downloads\/en\/datasheet\/ebablock-k-08.pdf","file_size":"","filename":"ebablock-k-08.pdf","download_count":"13","version_history":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ebablock\u00ae K 08 | ebalta Kunststoff GmbH<\/title>\n<meta name=\"description\" content=\"ebablock\u00ae K 08 from ebalta Kunststoff GmbH is available as rough boards and blocks.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ebablock\u00ae K 08 | ebalta Kunststoff GmbH\" \/>\n<meta property=\"og:description\" content=\"ebablock\u00ae K 08\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/\" \/>\n<meta property=\"og:site_name\" content=\"ebalta Kunststoff GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ebaltaKunststoffGmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T10:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ebablock\u00ae K 08 | ebalta Kunststoff GmbH","description":"ebablock\u00ae K 08 from ebalta Kunststoff GmbH is available as rough boards and blocks.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/","og_locale":"en_US","og_type":"article","og_title":"ebablock\u00ae K 08 | ebalta Kunststoff GmbH","og_description":"ebablock\u00ae K 08","og_url":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/","og_site_name":"ebalta Kunststoff GmbH","article_publisher":"https:\/\/www.facebook.com\/ebaltaKunststoffGmbH","article_modified_time":"2026-04-28T10:39:23+00:00","og_image":[{"width":600,"height":429,"url":"https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/#article","isPartOf":{"@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/"},"author":{"name":"rotabene","@id":"https:\/\/ebalta.com\/en\/#\/schema\/person\/7260f02159f21ed3544526ad2295921b"},"headline":"ebablock\u00ae K 08","datePublished":"2022-01-12T10:35:21+00:00","dateModified":"2026-04-28T10:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/"},"wordCount":2108,"publisher":{"@id":"https:\/\/ebalta.com\/en\/#organization"},"image":{"@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/#primaryimage"},"thumbnailUrl":"https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1.jpg","inLanguage":"en-US"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/","url":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/","name":"ebablock\u00ae K 08 | ebalta Kunststoff GmbH","isPartOf":{"@id":"https:\/\/ebalta.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/#primaryimage"},"image":{"@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/#primaryimage"},"thumbnailUrl":"https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1.jpg","datePublished":"2022-01-12T10:35:21+00:00","dateModified":"2026-04-28T10:39:23+00:00","description":"ebablock\u00ae K 08 from ebalta Kunststoff GmbH is available as rough boards and blocks.","breadcrumb":{"@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/#primaryimage","url":"https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1.jpg","contentUrl":"https:\/\/ebalta.com\/wp-content\/uploads\/pu-block-ebablock-K-08-lachs-1.jpg","width":600,"height":429,"caption":"ebablock K 08 - Model made of polyurethane block material"},{"@type":"BreadcrumbList","@id":"https:\/\/ebalta.com\/en\/produkte\/ebablock-k-08\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ebalta.com\/en\/"},{"@type":"ListItem","position":2,"name":"ebablock\u00ae K 08"}]},{"@type":"WebSite","@id":"https:\/\/ebalta.com\/en\/#website","url":"https:\/\/ebalta.com\/en\/","name":"ebalta Kunststoff GmbH","description":"Ihr kompetenter Partner mit der nachhaltigen PU-Kunststoffl\u00f6sung im Formen- und Werkzeugbau.","publisher":{"@id":"https:\/\/ebalta.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ebalta.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ebalta.com\/en\/#organization","name":"ebalta Kunststoff GmbH","url":"https:\/\/ebalta.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ebalta.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ebalta.com\/wp-content\/uploads\/2021\/06\/ebalta-logo-alternative.png","contentUrl":"https:\/\/ebalta.com\/wp-content\/uploads\/2021\/06\/ebalta-logo-alternative.png","width":155,"height":69,"caption":"ebalta Kunststoff GmbH"},"image":{"@id":"https:\/\/ebalta.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ebaltaKunststoffGmbH","https:\/\/www.xing.com\/pages\/ebalta-kunststoff-gmbh","https:\/\/de.linkedin.com\/company\/ebalta","https:\/\/www.instagram.com\/ebalta.career\/"]},{"@type":"Person","@id":"https:\/\/ebalta.com\/en\/#\/schema\/person\/7260f02159f21ed3544526ad2295921b","name":"rotabene","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/3a902e8e652ba3599cb47cd0ec0695cbc82274879b53a2aec0c029eba1b13b05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3a902e8e652ba3599cb47cd0ec0695cbc82274879b53a2aec0c029eba1b13b05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a902e8e652ba3599cb47cd0ec0695cbc82274879b53a2aec0c029eba1b13b05?s=96&d=mm&r=g","caption":"rotabene"},"sameAs":["https:\/\/ebalta.com"]}]}},"_links":{"self":[{"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/dlp_document\/4558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/media\/7043"}],"wp:attachment":[{"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/media?parent=4558"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/doc_categories?post=4558"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/doc_tags?post=4558"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/doc_author?post=4558"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/ebalta.com\/en\/wp-json\/wp\/v2\/file_type?post=4558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}